{"id":3280,"date":"2022-06-25T17:01:44","date_gmt":"2022-06-25T15:01:44","guid":{"rendered":"https:\/\/eggstedt.de\/cms\/wp-content\/uploads\/2022\/06\/DSC01846.jpg"},"modified":"2022-06-25T17:01:44","modified_gmt":"2022-06-25T15:01:44","slug":"dsc01846","status":"inherit","type":"attachment","link":"https:\/\/eggstedt.de\/cms\/endlich-wieder-kinderfest-in-eggstedt\/dsc01846\/","title":{"rendered":"DSC01846"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ngg_post_thumbnail":0},"class_list":["post-3280","attachment","type-attachment","status-inherit","hentry"],"catfolder_id":null,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/eggstedt.de\/cms\/wp-content\/uploads\/2022\/06\/DSC01846-scaled.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/eggstedt.de\/cms\/wp-content\/uploads\/2022\/06\/DSC01846-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/eggstedt.de\/cms\/wp-content\/uploads\/2022\/06\/DSC01846-300x200.jpg 300w, https:\/\/eggstedt.de\/cms\/wp-content\/uploads\/2022\/06\/DSC01846-1024x681.jpg 1024w, https:\/\/eggstedt.de\/cms\/wp-content\/uploads\/2022\/06\/DSC01846-768x511.jpg 768w, https:\/\/eggstedt.de\/cms\/wp-content\/uploads\/2022\/06\/DSC01846-1536x1022.jpg 1536w, https:\/\/eggstedt.de\/cms\/wp-content\/uploads\/2022\/06\/DSC01846-2048x1363.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1703,"file":"2022\/06\/DSC01846-scaled.jpg","sizes":{"medium":{"file":"DSC01846-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/eggstedt.de\/cms\/wp-content\/uploads\/2022\/06\/DSC01846-300x200.jpg"},"large":{"file":"DSC01846-1024x681.jpg","width":1024,"height":681,"mime_type":"image\/jpeg","source_url":"https:\/\/eggstedt.de\/cms\/wp-content\/uploads\/2022\/06\/DSC01846-1024x681.jpg"},"thumbnail":{"file":"DSC01846-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/eggstedt.de\/cms\/wp-content\/uploads\/2022\/06\/DSC01846-150x150.jpg"},"medium_large":{"file":"DSC01846-768x511.jpg","width":768,"height":511,"mime_type":"image\/jpeg","source_url":"https:\/\/eggstedt.de\/cms\/wp-content\/uploads\/2022\/06\/DSC01846-768x511.jpg"},"1536x1536":{"file":"DSC01846-1536x1022.jpg","width":1536,"height":1022,"mime_type":"image\/jpeg","source_url":"https:\/\/eggstedt.de\/cms\/wp-content\/uploads\/2022\/06\/DSC01846-1536x1022.jpg"},"2048x2048":{"file":"DSC01846-2048x1363.jpg","width":2048,"height":1363,"mime_type":"image\/jpeg","source_url":"https:\/\/eggstedt.de\/cms\/wp-content\/uploads\/2022\/06\/DSC01846-2048x1363.jpg"},"post-thumbnail":{"file":"DSC01846-604x270.jpg","width":604,"height":270,"mime_type":"image\/jpeg","source_url":"https:\/\/eggstedt.de\/cms\/wp-content\/uploads\/2022\/06\/DSC01846-604x270.jpg"},"full":{"file":"DSC01846-scaled.jpg","width":2560,"height":1703,"mime_type":"image\/jpeg","source_url":"https:\/\/eggstedt.de\/cms\/wp-content\/uploads\/2022\/06\/DSC01846-scaled.jpg"}},"image_meta":{"aperture":"4","credit":"Picasa","camera":"SLT-A58","caption":"","created_timestamp":"1655564536","copyright":"","focal_length":"18","iso":"100","shutter_speed":"0.004","title":"","orientation":"0","keywords":[]},"original_image":"DSC01846.jpg"},"post":3240,"source_url":"https:\/\/eggstedt.de\/cms\/wp-content\/uploads\/2022\/06\/DSC01846-scaled.jpg","_links":{"self":[{"href":"https:\/\/eggstedt.de\/cms\/wp-json\/wp\/v2\/media\/3280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eggstedt.de\/cms\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/eggstedt.de\/cms\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/eggstedt.de\/cms\/wp-json\/wp\/v2\/users\/1"}]}}